{"id":96,"date":"2021-04-11T19:03:44","date_gmt":"2021-04-11T17:03:44","guid":{"rendered":"https:\/\/fitshaker-eshop-new.goodrequest.com\/wp-content\/uploads\/2021\/04\/ranajky_slovensky.jpg"},"modified":"2021-04-11T19:03:44","modified_gmt":"2021-04-11T17:03:44","slug":"ranajky_slovensky-jpg","status":"inherit","type":"attachment","link":"https:\/\/fitshaker.sk\/eshop\/cs\/ranajky_slovensky-jpg","title":{"rendered":"ranajky_slovensky.jpg"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/ranajky_slovensky.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"300\" src=\"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/ranajky_slovensky-185x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/ranajky_slovensky-185x300.jpg 185w, https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/ranajky_slovensky-350x568.jpg 350w, https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/ranajky_slovensky.jpg 493w\" sizes=\"(max-width: 185px) 100vw, 185px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":493,"height":800,"file":"2021\/04\/ranajky_slovensky.jpg","filesize":210491,"sizes":{"woocommerce_thumbnail":{"file":"ranajky_slovensky-350x568.jpg","width":350,"height":568,"filesize":47308,"uncropped":true,"mime_type":"image\/jpeg","source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/ranajky_slovensky-350x568.jpg"},"woocommerce_gallery_thumbnail":{"file":"ranajky_slovensky-100x100.jpg","width":100,"height":100,"filesize":4465,"mime_type":"image\/jpeg","source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/ranajky_slovensky-100x100.jpg"},"medium":{"file":"ranajky_slovensky-185x300.jpg","width":185,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/ranajky_slovensky-185x300.jpg"},"thumbnail":{"file":"ranajky_slovensky-385x498.jpg","width":385,"height":498,"mime_type":"image\/jpeg","source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/ranajky_slovensky-385x498.jpg"},"shop_catalog":{"file":"ranajky_slovensky-450x450.jpg","width":450,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/ranajky_slovensky-450x450.jpg"},"shop_thumbnail":{"file":"ranajky_slovensky-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/ranajky_slovensky-100x100.jpg"},"full":{"file":"ranajky_slovensky.jpg","width":493,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/ranajky_slovensky.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/ranajky_slovensky.jpg","_links":{"self":[{"href":"https:\/\/fitshaker.sk\/eshop\/cs\/wp-json\/wp\/v2\/media\/96"}],"collection":[{"href":"https:\/\/fitshaker.sk\/eshop\/cs\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/fitshaker.sk\/eshop\/cs\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/fitshaker.sk\/eshop\/cs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fitshaker.sk\/eshop\/cs\/wp-json\/wp\/v2\/comments?post=96"}]}}