{"id":89800,"date":"2021-04-11T20:49:22","date_gmt":"2021-04-11T18:49:22","guid":{"rendered":"https:\/\/fitshaker-eshop-new.goodrequest.com\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4.jpg"},"modified":"2021-04-11T20:51:18","modified_gmt":"2021-04-11T18:51:18","slug":"fit-duo-na-rok-2019-fitness-diar-fitness-kalendar-7-2","status":"inherit","type":"attachment","link":"https:\/\/fitshaker.sk\/eshop\/cs\/fit-duo-na-rok-2019-fitness-diar-fitness-kalendar-7-2","title":{"rendered":"Fit DUO na rok 2019 &#8211; Fitness di\u00e1r + Fitness kalend\u00e1r 7"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"185\" src=\"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4-300x185.jpg\" class=\"attachment-medium size-medium\" alt=\"Fit DUO na rok 2019 - Fitness di\u00e1r + Fitness kalend\u00e1r\" srcset=\"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4-300x185.jpg 300w, https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4-600x369.jpg 600w, https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4-1024x630.jpg 1024w, https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4-768x472.jpg 768w, https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Fit DUO na rok 2019 - Fitness di\u00e1r + Fitness kalend\u00e1r","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":738,"file":"2021\/04\/Fitness-kalendar-2019-nalepky-4.jpg","filesize":450308,"sizes":{"woocommerce_thumbnail":{"file":"Fitness-kalendar-2019-nalepky-4-450x450.jpg","width":450,"height":450,"filesize":55404,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4-600x369.jpg"},"woocommerce_gallery_thumbnail":{"file":"Fitness-kalendar-2019-nalepky-4-100x100.jpg","width":100,"height":100,"filesize":4009,"mime_type":"image\/jpeg","source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4-100x100.jpg"},"woocommerce_single":{"file":"Fitness-kalendar-2019-nalepky-4-600x369.jpg","width":600,"height":369,"filesize":58805,"mime_type":"image\/jpeg","source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4-600x369.jpg"},"medium":{"file":"Fitness-kalendar-2019-nalepky-4-300x185.jpg","width":300,"height":185,"mime_type":"image\/jpeg","source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4-300x185.jpg"},"large":{"file":"Fitness-kalendar-2019-nalepky-4-1024x630.jpg","width":1024,"height":630,"mime_type":"image\/jpeg","source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4-1024x630.jpg"},"thumbnail":{"file":"Fitness-kalendar-2019-nalepky-4-385x498.jpg","width":385,"height":498,"mime_type":"image\/jpeg","source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4-385x498.jpg"},"medium_large":{"file":"Fitness-kalendar-2019-nalepky-4-768x472.jpg","width":768,"height":472,"mime_type":"image\/jpeg","source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4-768x472.jpg"},"shop_catalog":{"file":"Fitness-kalendar-2019-nalepky-4-450x450.jpg","width":450,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4-450x450.jpg"},"shop_single":{"file":"Fitness-kalendar-2019-nalepky-4-600x369.jpg","width":600,"height":369,"mime_type":"image\/jpeg","source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4-600x369.jpg"},"shop_thumbnail":{"file":"Fitness-kalendar-2019-nalepky-4-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4-100x100.jpg"},"full":{"file":"Fitness-kalendar-2019-nalepky-4.jpg","width":1200,"height":738,"mime_type":"image\/jpeg","source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/fitshaker.sk\/eshop\/wp-content\/uploads\/2021\/04\/Fitness-kalendar-2019-nalepky-4.jpg","_links":{"self":[{"href":"https:\/\/fitshaker.sk\/eshop\/cs\/wp-json\/wp\/v2\/media\/89800"}],"collection":[{"href":"https:\/\/fitshaker.sk\/eshop\/cs\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/fitshaker.sk\/eshop\/cs\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/fitshaker.sk\/eshop\/cs\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fitshaker.sk\/eshop\/cs\/wp-json\/wp\/v2\/comments?post=89800"}]}}